{"id":3831,"date":"2022-01-13T09:51:52","date_gmt":"2022-01-13T08:51:52","guid":{"rendered":"https:\/\/dame1minutode.org\/?p=3831"},"modified":"2022-01-13T09:51:52","modified_gmt":"2022-01-13T08:51:52","slug":"navidad-sin-turrones","status":"publish","type":"post","link":"https:\/\/dame1minutode.org\/en\/navidad-sin-turrones\/","title":{"rendered":"Navidad sin turrones"},"content":{"rendered":"\n<div class=\"wp-block-group\"><div class=\"wp-block-group__inner-container is-layout-flow wp-block-group-is-layout-flow\">\n<p><em>Por <em>Naiara N\u00e1jera Etxeandia<\/em>.<br>Alumna <em>del grado de Derecho y Comunicaci\u00f3n de la Universidad de Deusto. Campus de San Sebasti\u00e1n<\/em>.<\/em><\/p>\n<\/div><\/div>\n\n\n\n<hr class=\"wp-block-separator has-text-color has-background has-cyan-bluish-gray-background-color has-cyan-bluish-gray-color is-style-wide\"\/>\n\n\n\n<p>Durante las fiestas de Navidad, muchas personas nos hemos deleitado con la llegada de los turrones. Los turrones son ya algo tan t\u00edpico de la Navidad que si no hay alguno en casa no parece que sea Navidad. El 24, ya llegada la Nochebuena, cada hogar celebra la cena con comidas especiales. Algunas familias siguen una tradici\u00f3n a\u00f1o tras a\u00f1o y otras innovan cada Navidad. Hay familias m\u00e1s grandes y otras m\u00e1s peque\u00f1as, pero todas se unen en torno a una comida especial. El 25 continuamos con las grandes comidas, y fechas posteriores como el 31,1 o 6 de enero tambi\u00e9n son fechas donde hay alguna comida especial de por medio.<\/p>\n\n\n\n<p>Estas fechas tambi\u00e9n deber\u00edan recordarnos la gran injusticia que se sigue viviendo en torno a la comida. Mientras algunas familias pueden permitirse hacer comidas especiales en fechas especiales, hay otras familias que ni siquiera tienen qu\u00e9 comer en un d\u00eda normal. Por ello, Naciones Unidas decidi\u00f3 incluir como <a href=\"https:\/\/www.un.org\/sustainabledevelopment\/es\/hunger\/\" target=\"_blank\" rel=\"noreferrer noopener\">objetivo n\u00famero 2 <\/a>en los Objetivos de Desarrollo Sostenible poner fin al hambre. En este sentido, indica que desde hace una d\u00e9cada la cantidad de personas que padecen hambre ha ido aumentadohasta llegar a cerca de 690 millones, es decir, el 8,9 por ciento de la poblaci\u00f3n mundial. Adem\u00e1s, a\u00f1ade que, si no cambiamos el sistema agroalimentario actual, en 2030 podremos llegar a superar los 840 millones de personas que padecen hambre, y muchos de ellos empeorar\u00e1n las p\u00e9simas condiciones actuales hasta llegar al hambre severo y la hambruna.<\/p>\n\n\n\n<p>Por ello es indispensable que desde ya trabajemos en poner fin al hambre y asegurar el acceso de todas las personas a una alimentaci\u00f3n sana, nutritiva y suficiente. Los alimentos existen, s\u00f3lo nos queda compartirlos justamente y proteger a los productores de dichos alimentos reconociendo el valor que su trabajo tiene.<\/p>\n\n\n\n<p>Es obligaci\u00f3n de todos ser conscientes del problema ya que es un problema de todos. As\u00ed pues, disfrutemos de las comidas familiares esta Navidad y aprovechemos esta \u00e9poca para comer tantos turrones como podamos. No obstante, comamos con conciencia, sin malgastar ni echar nada, siempre conscientes de nuestra suerte y nuestra obligaci\u00f3n de ser parte de aquellos que luchan por una repartici\u00f3n de los alimentos equitativa.<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-embed-youtube wp-block-embed is-type-video is-provider-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<div class=\"videoWrapper\"><iframe loading=\"lazy\" title=\"ODS 2 | Hambre cero\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/W_NUWV7qgk0?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/div>\n<\/div><\/figure>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p><em><strong><em>Naiara N\u00e1jera Etxeandia<\/em>.<\/strong><br><\/em><a href=\"https:\/\/es.linkedin.com\/in\/naiara-n%C3%A1jera-etxeandia-474008209\"><em>https:\/\/es.linkedin.com\/in\/naiara-n%C3%A1jera-etxeandia-474008209<\/em><\/a><\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p><em>Imagen: Organizaci\u00f3n Mundial de la Salud (OMS)<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por Naiara N\u00e1jera Etxeandia.Alumna del grado de Derecho y Comunicaci\u00f3n de la Universidad de Deusto. Campus de San Sebasti\u00e1n. Durante las fiestas de Navidad, muchas personas nos hemos deleitado con la llegada de los turrones. Los turrones son ya algo tan t\u00edpico de la Navidad que si no hay alguno en casa no parece que [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":3829,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[522,519,532],"tags":[],"class_list":["post-3831","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agenda-2030-en","category-vida-en","category-derecho-a-la-alimentacion-en"],"acf":[],"_links":{"self":[{"href":"https:\/\/dame1minutode.org\/en\/wp-json\/wp\/v2\/posts\/3831","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dame1minutode.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dame1minutode.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dame1minutode.org\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dame1minutode.org\/en\/wp-json\/wp\/v2\/comments?post=3831"}],"version-history":[{"count":0,"href":"https:\/\/dame1minutode.org\/en\/wp-json\/wp\/v2\/posts\/3831\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dame1minutode.org\/en\/wp-json\/wp\/v2\/media\/3829"}],"wp:attachment":[{"href":"https:\/\/dame1minutode.org\/en\/wp-json\/wp\/v2\/media?parent=3831"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dame1minutode.org\/en\/wp-json\/wp\/v2\/categories?post=3831"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dame1minutode.org\/en\/wp-json\/wp\/v2\/tags?post=3831"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}