{"id":4528,"date":"2023-01-09T12:10:20","date_gmt":"2023-01-09T11:10:20","guid":{"rendered":"https:\/\/dame1minutode.org\/?p=4528"},"modified":"2023-01-09T12:10:20","modified_gmt":"2023-01-09T11:10:20","slug":"preestreno-del-documental-a-costa-dos-lancados","status":"publish","type":"post","link":"https:\/\/dame1minutode.org\/en\/preestreno-del-documental-a-costa-dos-lancados\/","title":{"rendered":"Preestreno del documental &#8220;A Costa dos Lan\u00e7ados&#8221;"},"content":{"rendered":"\n<p>El pr\u00f3ximo s\u00e1bado <strong>14 de enero a las 19:00 horas<\/strong>, en la sala Arrigunaga de <strong><a rel=\"noreferrer noopener\" href=\"https:\/\/goo.gl\/maps\/RJ1BRiu3BgTDCSyR8\" target=\"_blank\">Muxikebarri<\/a> &#8211; Centro de Arte, Cultura y Congresos de Getxo<\/strong>, tendr\u00e1 lugar el preestreno del documental &#8220;A Costa dos Lan\u00e7ados&#8221; escrito y dirigido por Unai Aranzadi y producido por UN Etxea.<\/p>\n\n\n\n<p><strong>La entrada es gratuita hasta completar aforo.<\/strong><\/p>\n\n\n\n<p>&#8220;A Costa dos Lan\u00e7ados&#8221; nos narra la llegada en el siglo XVI de los primeros europeos que exploraron los r\u00edos del \u00c1frica negra que fueron parias portugueses expulsados de la pen\u00ednsula ib\u00e9rica. M\u00e1s de quinientos a\u00f1os despu\u00e9s, otras personas, igualmente desesperadas, realizan el mismo trayecto, s\u00f3lo que esta vez en sentido contrario.<\/p>\n\n\n\n<p>El documental pretende hacer una reflexi\u00f3n sobre la dif\u00edcil situaci\u00f3n que se est\u00e1 viviendo en las costas de Guinea Bissau, Senegal y Gambia y hace una comparativa con la llegada de los primeros europeos a esas costas.<\/p>\n\n\n\n<p>En la sesi\u00f3n contaremos con la participaci\u00f3n de Unai Aranzadi qui\u00e9n al final de la proyecci\u00f3n contestar\u00e1 las preguntas del p\u00fablico.<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"724\" height=\"1024\" src=\"https:\/\/dame1minutode.org\/wp-content\/uploads\/2023\/01\/poster-costa-lanzadostx-724x1024.jpg\" alt=\"\" class=\"wp-image-4521\" srcset=\"https:\/\/dame1minutode.org\/wp-content\/uploads\/2023\/01\/poster-costa-lanzadostx-724x1024.jpg 724w, https:\/\/dame1minutode.org\/wp-content\/uploads\/2023\/01\/poster-costa-lanzadostx-212x300.jpg 212w, https:\/\/dame1minutode.org\/wp-content\/uploads\/2023\/01\/poster-costa-lanzadostx-768x1087.jpg 768w, https:\/\/dame1minutode.org\/wp-content\/uploads\/2023\/01\/poster-costa-lanzadostx.jpg 800w\" sizes=\"auto, (max-width: 724px) 100vw, 724px\" \/><\/figure>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El pr\u00f3ximo s\u00e1bado 14 de enero a las 19:00 horas, en la sala Arrigunaga de Muxikebarri &#8211; Centro de Arte, Cultura y Congresos de Getxo, tendr\u00e1 lugar el preestreno del documental &#8220;A Costa dos Lan\u00e7ados&#8221; escrito y dirigido por Unai Aranzadi y producido por UN Etxea. La entrada es gratuita hasta completar aforo. &#8220;A Costa [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":4526,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[528],"tags":[],"class_list":["post-4528","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-derechos-humanos-en"],"acf":[],"_links":{"self":[{"href":"https:\/\/dame1minutode.org\/en\/wp-json\/wp\/v2\/posts\/4528","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/dame1minutode.org\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/dame1minutode.org\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/dame1minutode.org\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/dame1minutode.org\/en\/wp-json\/wp\/v2\/comments?post=4528"}],"version-history":[{"count":0,"href":"https:\/\/dame1minutode.org\/en\/wp-json\/wp\/v2\/posts\/4528\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/dame1minutode.org\/en\/wp-json\/wp\/v2\/media\/4526"}],"wp:attachment":[{"href":"https:\/\/dame1minutode.org\/en\/wp-json\/wp\/v2\/media?parent=4528"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/dame1minutode.org\/en\/wp-json\/wp\/v2\/categories?post=4528"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/dame1minutode.org\/en\/wp-json\/wp\/v2\/tags?post=4528"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}